{"id":1257,"date":"2023-03-23T16:49:00","date_gmt":"2023-03-23T16:49:00","guid":{"rendered":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/?p=1257"},"modified":"2023-03-23T18:58:45","modified_gmt":"2023-03-23T18:58:45","slug":"tien-dagen-zonder-social-media","status":"publish","type":"post","link":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/2023\/03\/23\/tien-dagen-zonder-social-media\/","title":{"rendered":"Tien dagen zonder sociale media"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Welkom bij mijn podcast Tien Dagen Zonder. In deze rubriek kan je me horen terwijl ik tien dagen een bepaalde verslaving aan de kant schuif.<br><strong>door Thomas Vangampelaere<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De eerste aflevering gaat over de verslaving sociale media. Naarmate ik ouder werd merkte ik meer en meer dat sociale media een steeds prominentere rol is beginnen spelen in mijn leven en besteed ik ook steeds meer tijd op socials zoals Facebook en Instagram.<br>In deze podcast kan je horen hoe ik tien dagen zonder sociale media doorbreng. Dit hou ik bij aan de hand van een audiodagboek afgewisseld met enkele interessante quotes van mensen die om verschillende redenen al enkele keren hun sociale media  hebben verwijderd. Het is een relevant onderwerp, want volgens de VRT vinden zes op de tien jongeren tussen de 18 en 24 jaar zich te afhankelijk van sociale media. Ik vond dit een uitgelezen kans om dit bij mijzelf eens te testen en welk gevoel me dit zou geven. Ik dacht persoonlijk hier geen problemen mee te hebben, maar kwam toch uit op een verrassend resultaat. Ik wens jullie veel plezier bij het beluisteren van mijn podcast en ik zou zeggen, probeer het zeker ook eens!<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-soundcloud wp-block-embed-soundcloud\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Podcast 10 Dagen Zonder by User 173269228\" width=\"640\" height=\"400\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&#038;url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F1475605288&#038;show_artwork=true&#038;maxheight=960&#038;maxwidth=640\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Welkom bij mijn podcast Tien Dagen Zonder. In deze rubriek kan je me horen terwijl&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47,35,36,38],"tags":[],"class_list":["post-1257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-jongeren","category-maatschappij","category-podcast"],"_links":{"self":[{"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/posts\/1257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/comments?post=1257"}],"version-history":[{"count":3,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/posts\/1257\/revisions"}],"predecessor-version":[{"id":1262,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/posts\/1257\/revisions\/1262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/media\/1258"}],"wp:attachment":[{"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/media?parent=1257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/categories?post=1257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/journalistiek.mm.ehb.be\/erasmix\/wp-json\/wp\/v2\/tags?post=1257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}